{"id":1804476,"date":"2025-12-30T10:29:58","date_gmt":"2025-12-30T09:29:58","guid":{"rendered":"https:\/\/www.nosoinfo.be\/nosoinfos\/?p=1804476"},"modified":"2025-12-30T10:29:58","modified_gmt":"2025-12-30T09:29:58","slug":"la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci","status":"publish","type":"post","link":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/","title":{"rendered":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1798424\" src=\"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-750x500.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-750x500.jpg 750w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-1024x683.jpg 1024w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-768x512.jpg 768w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-1536x1024.jpg 1536w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-2048x1365.jpg 2048w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-228x152.jpg 228w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-80x53.jpg 80w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2 class=\"p1\"><b>Introduction<\/b><\/h2>\n<p class=\"p3\">La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants <sup>(1-4)<\/sup>. Jusqu\u2019\u00e0 r\u00e9cemment, les \u00e9quipes PCI se concentraient (au mieux) exclusivement sur la surveillance et la pr\u00e9vention de la pneumonie associ\u00e9e \u00e0 la ventilation assist\u00e9e (VAP). Ceci est \u00e0 noter car d\u2019apr\u00e8s des \u00e9tudes am\u00e9ricaines les 2\/3 de toutes les pneumonies nosocomiales surviennent chez des patients non ventil\u00e9s <sup>(5-6)<\/sup>. <br \/>En Europe, l\u2019impact des pneumonies nosocomiales non associ\u00e9es \u00e0 la ventilation (nv-HAP) a \u00e9t\u00e9 tr\u00e9s peu \u00e9tudi\u00e9. Les programmes nationaux de pr\u00e9vention de la nv-HAP, qu\u2019ils aient ou non \u00e9t\u00e9 \u00e9labor\u00e9s conform\u00e9ment \u00e0 la strat\u00e9gie d\u2019am\u00e9lioration multimodale de l\u2019OMS, sont absents <sup>7<\/sup>. L\u2019impact n\u00e9gatif de la nv-HAP sur les patients et le syst\u00e8me de sant\u00e9 est consid\u00e9rable <sup>4.8<\/sup>. Ce n\u2019est pas pour rien que les nv-HAP ont \u00e9t\u00e9 incluses dans les 10 points \u00e0 travailler les plus importants pour la s\u00e9curit\u00e9 des patients en 2022 par l\u2019ECRI (Emergency Care Research Institute). Malgr\u00e9 les diverses initiatives d\u2019action d\u00e9j\u00e0 formul\u00e9es<sup>7,9<\/sup>, l\u2019\u00e9laboration et la mise en oeuvre d\u2019une strat\u00e9gie d\u2019am\u00e9lioration multimodale pour la pr\u00e9vention de la nv-HAP s\u2019av\u00e8rent complexes. Cet article passe en revue quelques points sensibles, et \u00e9mets \u00e9galement des suggestions pour rendre cette approche possible et r\u00e9alisable.<\/p>\n<h2 class=\"p1\"><b>D\u00e9finition de la nv-HAP<\/b><\/h2>\n<p class=\"p3\">Dans le contexte europ\u00e9en, l\u2019utilisation de la d\u00e9finition du ECDC pour la pneumonie semble appropri\u00e9e. Cette d\u00e9finition de la surveillance est utilis\u00e9e, entre autres, dans les \u00e9tudes europ\u00e9ennes de pr\u00e9valence ponctuelle des infections nosocomiales dans les h\u00f4pitaux de soins aigus et est \u00e9galement utilis\u00e9e dans le protocole Sciensano pour la surveillance nationale des infections nosocomiales en soins intensifs (2004). Le CDC\/NHSN utilise une d\u00e9finition similaire, bien qu\u2019avec quelques nuances et une sous-cat\u00e9gorisation diff\u00e9rente des pneumonies.<\/p>\n<p class=\"p1\"><b><i>Fig.1 D\u00e9finition ECDC, CDC\/NHSN des nv-HAP <sup>3,10<\/sup><\/i><\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1798438\" src=\"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-750x532.jpg\" alt=\"\" width=\"750\" height=\"532\" srcset=\"http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-750x532.jpg 750w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-1024x727.jpg 1024w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-768x545.jpg 768w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-228x162.jpg 228w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-80x57.jpg 80w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP.jpg 1109w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"p1\"><b>Surveillance<\/b><\/h2>\n<p class=\"p3\">Mesurer, c\u2019est savoir, mais cartographier correctement les nv-HAP s\u2019av\u00e8re une t\u00e2che complexe et exige une charge de travail importante. Contrairement \u00e0 d\u2019autres infections associ\u00e9es aux soins de sant\u00e9, pratiquement tous les patients hospitalis\u00e9s peuvent \u00eatre consid\u00e9r\u00e9es comme \u00e0 risque. En l\u2019absence d\u2019une surveillance automatis\u00e9e ou semi-automatis\u00e9e, la surveillance continue est une t\u00e2che impossible compte tenu des effectifs insuffisants de personnel PCI actuellement disponible dans nos h\u00f4pitaux. Pour contourner le probl\u00e8me de la surveillance longue et complexe, les codes ICD-10 sont parfois utilis\u00e9s pour les pneumonies qui surviennent apr\u00e8s 48 heures d\u2019hospitalisation et qui ne sont pas pr\u00e9sentes \u00e0 l\u2019admission. Cette m\u00e9thode est associ\u00e9e \u00e0 une faible sensibilit\u00e9 et sp\u00e9cificit\u00e9 et est en outre influenc\u00e9e par la variabilit\u00e9 interhospitali\u00e8re de la qualit\u00e9 du codage ICD10 <sup>4,11,12<\/sup>. Ainsi, dans une \u00e9tude Suisse Mueller et al. rapportaient, par ex. une sensibilit\u00e9 de 53,7 % <sup>12<\/sup>. L\u2019utilisation des donn\u00e9es de r\u00e9sum\u00e9 cliniques minimum (RCM) n\u2019est g\u00e9n\u00e9ralement pas recommand\u00e9e comme technique de surveillance et conduit souvent \u00e0 une sous-estimation. Dans un contexte diff\u00e9rent, une \u00e9tude belge arrive \u00e0 la m\u00eame conclusion<sup>13<\/sup>.<\/p>\n<p class=\"p3\">En raison de l\u2019utilisation g\u00e9n\u00e9ralis\u00e9e des dossiers de sant\u00e9 \u00e9lectroniques, l\u2019introduction de la surveillance (semi-)automatis\u00e9e offre une solution prometteuse <sup>14-15<\/sup>. Dans la surveillance automatis\u00e9e, des logiciels (algorithmes ou syst\u00e8mes d\u2019apprentissage automatique) permettent de d\u00e9tecter des \u00e9pisodes de nv-HAP via les donn\u00e9es des dossiers patients \u00e9lectroniques, les param\u00e8tres vitaux, les r\u00e9sultats de laboratoire, les rapports RX, etc. Avec la surveillance enti\u00e8rement automatis\u00e9e, il n\u2019est pas n\u00e9cessaire de confirmer manuellement les cas d\u2019infection d\u00e9tect\u00e9s. Dans le cadre d\u2019une surveillance semi-automatis\u00e9e, le logiciel identifie les cas suspects sur la base de crit\u00e8res d\u00e9finis. Dans un second temps, une analyse manuelle des dossiers suspects est effectu\u00e9e afin de d\u00e9terminer s\u2019il s\u2019agit r\u00e9ellement d\u2019une nv-HAP. La sensibilit\u00e9, la sp\u00e9cificit\u00e9 et la r\u00e9duction possible de la charge de travail de divers algorithmes pour la surveillance semi-automatis\u00e9e de nv-HAP ont \u00e9t\u00e9 \u00e9tudi\u00e9es \u00e0 \u00e0 l\u2019h\u00f4pital universitaire de Z\u00fcrich <sup>12<\/sup>.<\/p>\n<p class=\"p3\">L\u2019utilisation de ces algorithmes d\u00e9pend des usages locaux et de la mani\u00e8re dont toutes les donn\u00e9es n\u00e9cessaires sont enregistr\u00e9es de mani\u00e8re structur\u00e9e dans le syst\u00e8me d\u2019information hospitalier. De nombreux algorithmes prometteurs rapport\u00e9s dans une \u00e9tude monocentrique ne peuvent pas \u00eatre simplement adopt\u00e9s sans que ceux-ci n\u2019aient fait la preuve d\u2019une validation locale pr\u00e9alable <sup>16<\/sup>. Une sensibilit\u00e9 \u00e9lev\u00e9e de d\u00e9tection est le param\u00e8tre le plus important dans la surveillance (semi-)automatis\u00e9e, un minimum de 90 % est n\u00e9cessaire <sup>17<\/sup>. Bien que les donn\u00e9es d\u2019une \u00e9tude monocentrique limitent la g\u00e9n\u00e9ralisation, elles peuvent tout de m\u00eame \u00eatre une bonne source d\u2019inspiration pour commencer. Dans l\u201d\u00e9tude Suisse mentionn\u00e9e ci-dessus, une sensibilit\u00e9 de 99,3 % a \u00e9t\u00e9 obtenue en combinant \u00ab proc\u00e9dure radiographique thorax \u00bb et \u00ab fi\u00e8vre &gt;38 \u00b0C ou un nombre anormal de globules blancs \u00bb. Cet algorithme a permis de r\u00e9duire la charge de travail de 91,1 % <sup>12<\/sup>.<span class=\"Apple-converted-space\">\u00a0 <\/span><br \/>Si l\u2019on veut faire une surveillance p\u00e9riodique de nv-HAP et mesurer l\u2019effet des actions pr\u00e9ventives prises, une sensibilit\u00e9 de 90 % para\u00eet suffisante <sup>12<\/sup>. Compte tenu du fait qu\u2019il est pr\u00e9f\u00e9rable de s\u2019efforcer \u00e9galement d\u2019obtenir la r\u00e9duction la plus \u00e9lev\u00e9e de la charge de travail, 3 algorithmes semblent int\u00e9ressants (voir figure 2).<\/p>\n<p class=\"p3\"><b><i>Fig.2. Algorithmes prometteurs pour la surveillance semi-automatis\u00e9e de nv-HAP <sup>12<\/sup>.<\/i><\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1798437\" src=\"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-750x338.jpg\" alt=\"\" width=\"750\" height=\"338\" srcset=\"http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-750x338.jpg 750w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-1024x462.jpg 1024w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-768x346.jpg 768w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-228x103.jpg 228w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01-80x36.jpg 80w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-01.jpg 1151w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">Une solution r\u00e9alisable pourrait consister \u00e0 recourir \u00e0 une surveillance semi-automatis\u00e9e, limit\u00e9e ou non \u00e0 certains services \u00e0 risque (par exemple, neurologie, oncologie\/h\u00e9matologie, g\u00e9riatrie, etc.) pendant quelques mois (par exemple, pendant la p\u00e9riode hivernale). Une telle approche permettrait \u00e9galement de valider l\u2019algorithme utilis\u00e9.<\/p>\n<p class=\"p1\">La grande variabilit\u00e9 des m\u00e9thodes de surveillance se traduit par un manque de donn\u00e9es de r\u00e9f\u00e9rence fiables. Les informations sur la pr\u00e9valence ou sur l\u2019incidence de la nv-HAP sont rares <sup>11<\/sup> (et il est toujours n\u00e9cessaire d\u2019examiner la mani\u00e8re dont les donn\u00e9es ont \u00e9t\u00e9 recueillies. La Fig. 3 \u00e9num\u00e8re quelques chiffres d\u2019incidence rapport\u00e9s.<\/p>\n<p class=\"p1\"><b><i>Fig.3. Incidence des nv-HAP<\/i><\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1798436\" src=\"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-750x131.jpg\" alt=\"\" width=\"750\" height=\"131\" srcset=\"http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-750x131.jpg 750w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-1024x178.jpg 1024w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-768x134.jpg 768w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-228x40.jpg 228w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02-80x14.jpg 80w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-02.jpg 1086w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"p1\"><b>Strat\u00e9gies de pr\u00e9vention<\/b><\/h2>\n<p class=\"p3\">Des donn\u00e9es fiables sur les actions pr\u00e9ventives efficaces sont limit\u00e9es. Il s\u2019agit souvent d\u2019\u00e9tudes non randomis\u00e9es qui ne mentionnent pas dse crit\u00e8res objectifs tels que la dur\u00e9e du s\u00e9jour, la mortalit\u00e9 ou l\u2019utilisation d\u2019antibiotiques <sup>21<\/sup> .<span class=\"Apple-converted-space\">\u00a0 <\/span>En raison des diff\u00e9rentes d\u00e9finitions et m\u00e9thodologies de surveillance, il est \u00e9galement difficile d\u2019\u00e9valuer les r\u00e9sultats rapport\u00e9s des strat\u00e9gies de pr\u00e9vention utilis\u00e9es.<br \/>Sur la base de l\u2019aper\u00e7u des facteurs de risque pour le d\u00e9veloppement de nv-HAP, les strat\u00e9gies de pr\u00e9vention suivantes visant les facteurs de risque modifiables peuvent \u00eatre propos\u00e9es <sup>21-23<\/sup>.<\/p>\n<p class=\"p3\"><b>Soins bucco-dentaires quotidiens pour tous les patients.<span class=\"Apple-converted-space\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<br \/><\/span><\/b>Cette intervention est la plus \u00e9tudi\u00e9e et est mentionn\u00e9e dans les \u00e9tudes avant-apr\u00e8s.<span class=\"Apple-converted-space\">\u00a0 <\/span>Elle vise \u00e0 r\u00e9duire le taux de colonisation du pharynx buccal par des bact\u00e9ries pathog\u00e8nes. Ce que ces soins bucco-dentaires quotidiens impliquent exactement n\u2019est pas toujours clairement d\u00e9fini 21<span class=\"Apple-converted-space\">\u00a0 <\/span>, mais de plus en plus de preuves soulignent la grande importance du brossage des dents tandis que l\u2019utilisation standard d\u2019un bain de bouche contenant de la chlorhexidine est abandonn\u00e9e <sup>2,21,24-25<\/sup>. <br \/>Le brossage m\u00e9canique des dents emp\u00eache la formation de la plaque dentaire et la formation de biofilm beaucoup mieux que les antiseptiques oraux. Les meilleures pratiques de soins buccodentaires bas\u00e9s sur des preuves (p. ex. celles pr\u00e9conis\u00e9es par l\u2019American Dental Association) devrait servir de base aux infirmiers pour prendre en charge quotidiennement le patient <sup>22<\/sup>.<br \/><span class=\"Apple-converted-space\">\u00a0\u00a0<br \/><\/span><b>D\u00e9pistage des troubles de la d\u00e9glutition en cas de suspicion de probl\u00e8mes de d\u00e9glutition\/ajustement du r\u00e9gime alimentaire et de l\u2019apport hydrique.<br \/><\/b>Cette intervention s\u2019adresse principalement aux patients victimes d\u2019un AVC, mais aussi aux patients g\u00e9riatriques et \u00e0 certains patients oncologiques <sup>26-27<\/sup>. Elle vise \u00e0 pr\u00e9venir l\u2019aspiration. Cette strat\u00e9gie de pr\u00e9vention comprend la mise en \u0153uvre d\u2019une politique claire de d\u00e9pistage au chevet du patient, l\u2019utilisation d\u2019un ou de plusieurs outils de d\u00e9pistage de la dysphagie et l\u2019\u00e9laboration de lignes directrices sur les menus de dysphagie dans lesquels la consistance des aliments et des boissons est d\u00e9termin\u00e9e en fonction du degr\u00e9 de dysphagie.<span class=\"Apple-converted-space\">\u00a0 <\/span>Le cadre IDDSI (International Dysphagia Diet Standardization Initiative) est une ligne directrice utile pour la cuisine di\u00e9t\u00e9tique et l\u2019orthophonie. La mesure dans laquelle l\u2019\u00e9l\u00e9vation de la t\u00eate du lit (30-45\u00b0) joue un r\u00f4le dans la pr\u00e9vention de la nv-HAP pendant les repas ou la nutrition ent\u00e9rale n\u2019a pas \u00e9t\u00e9 suffisamment \u00e9tudi\u00e9e <sup>21-22<\/sup> .<\/p>\n<h2 class=\"p1\"><b>Mobilisation pr\u00e9coce des patients<\/b><\/h2>\n<p class=\"p1\">Faire de l\u2019exercice en toute s\u00e9curit\u00e9 le plus t\u00f4t possible apr\u00e8s l\u2019admission ou l\u2019intervention chirurgicale pr\u00e9sente de nombreux avantages, tant sur le plan physique que mental, et semble \u00e9galement \u00eatre utile pour la pr\u00e9vention de nv-HAP <sup>29-32<\/sup>. <br \/>En plus de programmes de physioth\u00e9rapie adapt\u00e9s \u00e0 des groupes de patients sp\u00e9cifiques, il est n\u00e9cessaire de mettre en place une politique g\u00e9n\u00e9rale (par exemple, s\u2019asseoir sur le bord du lit ou se lever au moins 2 fois par jour, prendre ses repas hors du lit si possible).<\/p>\n<h2 class=\"p1\"><b>Interventions multimodales pour la pr\u00e9vention des pneumonies virales.<\/b><\/h2>\n<p class=\"p3\">20 \u00e0 40 % des nv-HAP sont d\u2019origine virale <sup>21<\/sup>. La pand\u00e9mie de covid-19 a donn\u00e9 lieu \u00e0 la pr\u00e9paration d\u2019un plan hivernal pour les infections respiratoires <sup>33<\/sup> dans lequel diverses mesures sont propos\u00e9es en fonction de l\u2019ampleur de la circulation des agents pathog\u00e8nes respiratoires viraux. Une nouvelle version est attendue \u00e0 l\u2019automne 2025. L\u2019utilisation de masques faciaux, <span class=\"Apple-converted-space\">\u00a0 <\/span>le d\u00e9pistage viral des patients symptomatiques, l\u2019isolement, la ventilation sont des \u00e9l\u00e9ments importants. Selon le CSS, une vaccination ad\u00e9quate contre le covid-19; RSV et la grippe saisonni\u00e8re dans les groupes \u00e0 haut risque contribue \u00e9galement \u00e0 la pr\u00e9vention du nv-HAP. La vaccination peut non seulement contribuer \u00e0 la pr\u00e9vention des pneumonies virales. Dans des groupes \u00e0 risque sp\u00e9cifiques, l\u2019administration d\u2019un vaccin antipneumococcique est \u00e9galement indiqu\u00e9e <sup>34<\/sup>.<\/p>\n<p class=\"p3\">Bien que parfois mentionn\u00e9e dans les care bundle de soins, l\u2019association entre la pr\u00e9vention des ulc\u00e8res de stress et la nv-HAP n\u2019est pas claire <sup>21,23<\/sup>. Aucune \u00e9tude ne d\u00e9montre que la pr\u00e9vention des ulc\u00e8res de stress est utile dans la pr\u00e9vention des nv-HAP.<\/p>\n<p class=\"p3\">Un nombre limit\u00e9 de publications font \u00e9tat de l\u2019utilisation de care bundle efficaces. La figure 4 en donne un aper\u00e7u <sup>23<\/sup>. Les \u00e9l\u00e9ments inclus dans les care bundles varient et sont rarement d\u00e9crits en d\u00e9tail.<span class=\"Apple-converted-space\">\u00a0 \u00a0<\/span><\/p>\n<p class=\"p3\"><b><i>Fig. 4 Care bundles pour la pr\u00e9vention des nv-HAP<\/i><\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1798438\" src=\"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-750x532.jpg\" alt=\"\" width=\"750\" height=\"532\" srcset=\"http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-750x532.jpg 750w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-1024x727.jpg 1024w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-768x545.jpg 768w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-228x162.jpg 228w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP-80x57.jpg 80w, http:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/MVHAP.jpg 1109w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/p>\n<h2 class=\"p1\"><b>Conclusion<\/b><\/h2>\n<p class=\"p3\">\u00c0 ce jour, la Belgique n\u2019est pas encore pr\u00eate pour une bonne surveillance automatis\u00e9e des nv-HAP. Il n\u2019y a pas de programme de surveillance formalis\u00e9. Il n\u2019existe pas non plus de recommandations nationales fond\u00e9es sur des donn\u00e9es probantes pour la pr\u00e9vention de la nv-HAP.<br \/>Ces manques existent en fait au niveau de l\u2019Europe dans son ensemble.<br \/>Des mesures relativement simples<sup>39-40<\/sup> peuvent pr\u00e9venir la nv-HAP, mais il n\u2019est pas facile d\u2019atteindre une conformit\u00e9 suffisante de l\u2019ensemble des soins<span class=\"Apple-converted-space\">\u00a0 <\/span>\u00e0 l\u2019\u00e9chelle de l\u2019h\u00f4pital. La mise en place de soins bucco-dentaires ad\u00e9quats 2 fois par jour pour tous les patients est un d\u00e9fi majeur <sup>2<\/sup>. Th\u00e9oriquement, il devrait \u00eatre facile de mesurer l\u2019observance des care bundles \u00e0 l\u2019aide des donn\u00e9es du dossier \u00e9lectronique du patient, mais la pratique montre que ce n\u2019est pas aussi simple. Il faut \u00e9galement y r\u00e9fl\u00e9chir.<br \/>Le nouvel ensemble d\u2019indicateurs de qualit\u00e9 f\u00e9d\u00e9raux CHIPS (Check Hospital Infection Prevention Status) qui entrera en vigueur \u00e0 partir de 2026 inclut explicitement la pr\u00e9vention des nv-HAP. Une strat\u00e9gie d\u2019am\u00e9lioration multimodale compos\u00e9e de proc\u00e9dures, de formation et d\u2019\u00e9ducation, de care bundle (mesure) et de surveillance est attendue sur une p\u00e9riode de 3 ans. En l\u2019absence d\u2019un programme national, ce sera une t\u00e2che difficile pour de nombreux h\u00f4pitaux.<\/p>\n<h2 class=\"p1\"><b>R\u00e9f\u00e9rences<\/b><\/h2>\n<p class=\"p3\">1. Mitchell (B.) et al., Strategies to reduce non-ventilator associated hospital-acquired pneumonia: a systematic review, Infect Dis Health, 2019, nov 24(4):229-239.<br \/>2. Munro (S.), Baker (D.), Reducing missed oral care opportunities to prevent non-ventilator associated hospital acquired penumonie at the Department of veterans Affairs, Applied Nursing Research, 2018, 44, 48-53.<br \/>3. European Centre for Disease Prevention and Control. Point prevalence survey of healthcare associated infections and antimicrobial use in European acute care hospitals. Stockholm: ECDC; 2024.<br \/>4. Baker (D.) et al., Impact of hospital-acquirted pneumonia on the Medicare program, Infect Control &amp; Hosp Epidemiol, 2024, 45, 316-321.<br \/>5. Magill (S.) et al., Changes in prevalence of healthcare-associated infections in US hospitals, N Engl J Med, 2018,379,13.<br \/>6. Jones (B.E.) et al., Incidence and outcomes of non-ventilator-associated hospital-acquired pneumonia in 284 US hospitals using electronic surveillance criteria, JAMA Network open, 2023, 6(5):e2314185.<br \/>7. Munro (S.) et al., Nonventilator hospital-acquired pneumonia: a call to action, Infect Control &amp; Hosp Epidemiol, 2021, 42(8), 991-996<br \/>8. Ji (W.) et al., Development and assessment of objective surveillance definitions for nonventilator hospital-acquired pneumonia, JAMA Netw open, 2019, 2 (10) , e913674<br \/>9. The Joint Commission, Preventing nonventilator hospital-acquired pneumonia, Quick Safety, issue 61, sept 2021.<br \/>10. NHSN, Pneumonia (Ventilator-associated [VAP] and non-ventilatorassociated Pneumonia [PNEU]) Event, january 2025, p.10.<br \/>11. Wolfensberger (A.) et al., Development and validation of a semi-automated surveillance system- lowering the fruit for non-ventilator-associated hospital-acquired pneumonia (nvHAP) prevention, Clinical Microbiology and Infection, 2019, 25, 1428.e7-1428.e13.<br \/>12. Mueller (A.) et al., Development and validation of selection algorithms for a non-ventilator hospital-acquired semi-automated surveikllance system, Clinical Microbiology and Infection, 2025, 31:582-587.<br \/>13. Martens (A.), Vermijdbare ziekenhuisinfecties Resultaten validatie-oefening: Vergelijken van Sciensano surveillance gegevens en Minimale Ziekenhuisgegevens voor bloedstroominfecties en Clostridioides difficile-darmwandinfecties, Sciensano maart 2025.<br \/>14. Wolfensberger (A.), Scherrer (A.), Sax (H.), Automated surveillance of non-ventilator-associated hospital-acquired pneumonie (nvHAP): a systematic literature review, ARIC, 2024 13:30.<br \/>15. Manzoor (F.), Rhee (C.), Klompas (M.), Semi-automated versus fully automated surveillance fo non-ventilator hospital-acquired pneumonia: going fort he gold when bronze is all there is, Clinical Microbiology and Infection, 2025, 31, 500-502.<br \/>16. Stern (S.E.) et al., Electronic surveillance criteria for non-ventilator-associated hospital-acquired pneumonia: assessment of reliability and validity, Infect Control &amp; Hosp Epidemiol 2023, 44, 1769-1775.<br \/>17. Van Mourik (M.) et al., PRAISE: Providing a roadmap for automated infection surveillance in Europe, Clin Microbiol Infect, 2021, 27:S3-19.<br \/>18. Giuliano (K.) et al., The epidemiology of nonventilator hospital-acquired pneumonia in the United States, Am J Infect Control, 2018, vol. 46, nr. 3, 322-327.<br \/>19. Carey (E.) et al., Non-ventilator associated hospital acquired pneumonia incidence and health outcomes among US veterans from 2016-2020. Am J Infect Control, 2022, 520,116-119.<br \/>20. Wolfensberger (A.) et al., Prevention of non-ventilator-associated hospital-acquired pneumonia in Switzerland: a type 2 hybrid effectiveness-implementation trial, Lancet infect Dis, 2023, 23:836-846.<br \/>21. Klompas (M.) et al., Strategies to prevent ventilator-associated pneumonia, ventilator-associated events and nonventilator hospital-acquired pneumonia in acute care hospitals: 2022 update, Infect Control &amp; Hosp Epidemiol, 2022, 43, 687-713.<br \/>22. Quinn (B.) et al., Non-ventilator healthcare-associated pneumonie (nvHAP): best practices for prevention of nv-HAP, Am J Infect Control, 2020, 48, A23-A27.<br \/>23. Livesey (A.) et al., Practices to prevent non-ventilator hospital acquired pneumonia: a narrative review, J Hosp Infect, 2024, 151, 201-212.<br \/>24. Ehrenzeller (S.), Klompas (M.), Association between daily toothbrushing and hospital-acquired pneumonia: a systematic review and meta-analysis, JAMA Internal Medicine, 2024, 184(2), 131-142<br \/>25. Crist (M.) et al., Oral care in non-ventilated hospitalized patients, Am J Infect Control, 2025, 53, 277-288<br \/>26. Rosario (B.) et al., Evaluation of multi-component interventions for prevention of nosocomial pneumonia in older adults: a randomized, controlled trial, European Geriatric Medicine, 2021, 12, 1045-1055.<br \/>27. Green (L.), Non-ventilator healthcare associated pneumonia (nvHAP): oncology, Am J Infect Control, 2020, 48, A20-22.<br \/>28. Passaro (L.), Harbarth (S.), Landelle (C.), Prevention of hospital-acquired pneumonia in non-ventilated adult patients, ARIC, 2016, 5:43.<br \/>29. Boden (I.) et al., Preoperative physiotherapy for the prevention of respiratory complications after upper abdominal surgery: pragmatic, double blinded multicentre randomised controlled trial, BMJ 2018:360:j5916.<br \/>30. Cuesy (P.) et al., Reduction in the incidence of poststroke nosocomial pneumonia by using the turn-mob program, J Stroke Cerebrovasc Dis, 2010:19(1)23-8.<br \/>31. Stolbrink (M.) et al., The early mobility bundle: a simple enhancement of therapy which may reduce incidence of hospital-acquired pneumonia and length of stay, J Hosp Infect 2014,88(1)34-39.<br \/>32. Qi (W.) et al., Association between daily average of mobility achieving during therapy sessions and hospital-acquired or ventilator associated pneumonia among critically ill patients, J Intensive Care Med, 2023, 38(5), 418-424.<br \/>33. RMG, Seizoensplan respiratoire pathogenen\/winterplan luchtweginfecties, 2024.<br \/>34. -, Vaccinatie tegen pneumokokkken (volwassenen), HGR nr. 9674, september 2022.<br \/>35. Kazaure (H.) et al., Long-term results of a postoperative pneumonia prevention program fort he inpatient surgical ward, JAMA Surg, 2014, 149(9), 914-918.<br \/>36. Lacerna (C.) et al., A succesful program preventing nonventilator hospital acquired pneumonia in a large hospital, Infect Control &amp; Hosp Epidemiol, 2020, 41, 547-552.<br \/>37. de Asis (M.) et al.,<span class=\"Apple-converted-space\">\u00a0 <\/span>The impact of a bundle to prevent hospital-acquired pneumonia in a cohort of nonventilated patients on enteral nutrition, Infect Control &amp; Hosp Epidemiol., 2021, 42, 100-102.<br \/>38. Sopena (N.) et al., Intervention to reduce the incidence of non-ventilator-associated hospital-acquired pneumonia: a pilot study, Am J Infect Control, 2023, 51, 1324-1328.<br \/>39. Davilla (S.), Non-ventilator healthcare associated peneumonia (nv-HAP): taking action to improve nv-HAP outcomes, Am J Infect Control, 2020, 48, A28-A35.<br \/>40. Patient Safety Movement Foundation,<span class=\"Apple-converted-space\">\u00a0 <\/span>Non-ventilator Hospital-acquired Pneumonia (nv-HAP) actionable patient safety solutions, 2022.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">\u00a0<\/p>\n<p class=\"p1\">\u00a0<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" target=\"pdf24PopWin\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\"><input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLy\/Xy8svzs\/MS8vXS0rVh7GLAQ==\" \/><input type=\"hidden\" name=\"blogName\" value=\"8\/MP9lfw9HPzBwA=\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"M7QwMDExNwMA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"VY4xDgMhDAS\/4vKuuA+ki6JIiZTivoDAJ1nibAKY96Slzw\/4WIAu3c5au+uXgRBbLciZhMFhgsCopzB1yZLEyknGT+DNpG5Qqx3bB7yBGfRmhhcu2+O6rxfQAaIFja7gWj0IgmiEUdPqWyl04fBvGvNwrHCO7etxvkJ8oB3XBMt9vz3XHw==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"TY5RDgMhCERPxPrf21CXzZK4QFX0+kWTJv1iGHgMd+\/WXinNOQ\/RpiyXHm9KP91SQbBKg6SzCpzUwIT8UeGQay3rw1h2I4AtDKboEILcWMGNyoAbDTyU+iD0OHYxmHqFhdPH2aKe9B9IfRlZpVcttPPjL8prGIxlTl8=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"8wkCAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtU1NNI1NlAwNLAyNLIytQAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"7VzLbhxJdt37KwICPCgCVSQrq0gW2WoBbErTzR6pRxanewwPBkZWZlRVSFmZ2RmZRVKr+QevvDDQ8MatMWDMYnbjVRP+EX+Jz73xyMh6SFSbGnhhYKZFsjLjcePec899RD0unzxWy7nIijhV+fzzR1n89vaRSGVSmN9jfZsnj0SSxVp\/\/kirt3KwlKlqluK6HKhlPJeD4cnpZByNHwldJZ8\/WtR1qc8ODq6vr\/fzQhcqnxX7U3ngftYHeDEp8lrm9UFT0sT6IDqMjg6G0UH89h\/nVSFzTC3\/8U1R1ZV6\/WZwcnR4c3R4uP+6nD8ScVZ\/\/uiRuFZpvfj8ET56JBZSzRf4K57hRWhZm3V8smUI\/HzdFw8\/x\/AwGt8cT0Y8Cf3ySWY5OZ7cHA0js5PjyafZydHo+IZ2YLaC3z7JNNHheHIzHB0f8TT026eZJsIsR0Zi+PmTzDGBepmDnxxeQ5FhazC5uKmLvugt45sB6\/wZ6V55swftOFxhHfzbI3Hw5PFB+eRvHi8iZ6vl8NGTx9Mnl3ldFWmT1KrIHx9M8dgiwnOlf2z06MnzWJS5bJZFrqSQuhbZf\/\/hn7ELyW8JPFck6u6dFHFzI2h\/GgghdJzXd+9E7\/L8ak9kGCJrtEiKpsLfpUhjPJVJgUHxrKx53Hakux9Ek9On1VSlCuP03e91nNHv9EqTY7y7v9RCLUv6IK+1eKyb8klvOBjvPT6gH\/fF143+vsGCMWR19y6RyyVk3sfcWty9+75RJX54eXEptMRoeYIPq1jhv6IXN2KpZANhypsEq1crSe8K3VS0IfyzkirLYrxEy6E9YoYVHiGxYFtZKLjO5vAJP5fFToRK1\/RZ77vzl3v74kImikWCZ\/OilpVI4kqk2EaMOX4kAdPy64b+jZd37yqVxCqXmvcVHYxo+rpoavsXvwwtSAWTYqli+jvtAZvNaVvJQr7lcUssSpIwcyzNLPPunRPt0eDYi\/bxtIJmPcvFs6YqStk3irEs46Q2A+2YNQ+1Rm+RRy9fDb6CIERMm8Rp1xWtoJSN2TTe2xfPaYaqmFcxjhSD8qukgtj65kGYEfuCdUFlkBofctHwaswsd++yeFrwVFCFWVFBsHziZoUamoHH5jhMPgl8mqmiMkteNlmtlkWKDfKMeODXL676sAe8H0+19Np54sT3vJVWjmExzqyzWKNo4YGQlsGybqErPy5lYGWkKliyVilUIZ7iIZ5qvD9xk11IkWM+erCMMSQMUVQYFQKRPImdk5ZrpKFyUnp8Ym1VA1PwnqKFQCAQxiqG+ku7RjLvwBB5AhIabK6p2GQ7uoWZgXcR\/lCxsJ5dvLoUvWdLWc1lntyKi7iS4pXUMq6ShbjMda1qqDNs40WczXFGPGsKm6xojSpXtcLYK\/ojHY7BJojjNdZKR9lkpGzmBPqnRixGY+2xm3M0hrxUgAMssZDNqjLHTfhzbw1wu9+lh0LT66u7Hyu2vGJZZvJGajomaEtVq4QGgY3wKiq5wiHhoDL8X7szgEpphaPWfVo0aSodDPQoMzCVsn3P5zhyTO+OXOYpNpTIGiAcl7AfmD0+0jwUDYQVA2I1KdH+Dqfx9O7djAW+tqtdDuSpBXt2eDeYWBJe4DhycwANDB8zBuOl4QyNeHbx9KKVqYdULZe0aN5GWRGYsADJvWyssIvWsAIzKd6B+ID55L3wXwjTq7vDV79awlcHLpAyjVTCZdQ4GLZ6UkPrFdcQz4+5uPtzqWqLUsZXxmreaOcCg\/PzC\/TOEtusMSZ+ukpgRbD9orWzcH8WCz+wKGiWWYEiHqLVTItedHg43iNsFRD5wTdfXX1j1yHZAYdy1WoJvFYVBDg1QMI6LZNWU\/OGlqONs6b9NnqQsAUVlT9wNZsBtCSzgo7TsOpXrmnfY\/Xkl2q+PxShGpKG9Ns1py2gscWP+sNDY\/KPD9QTo6c89gPFN6PJQ8Q3L77Dgk0gMYo+HM+MooeJZzamfYD4xYzJ8cpJdPJQ8YpdKcUn46MHik\/MmMzgjx+KwZsxibGfOMb+AAMaKQ4PT382\/S+f\/CKf6vKzv9ZvG57jKkCpXd7ihQSWyaovEstXdLwqFH5fxkoTD66J85ULRay4qCpgmwHMgMW07pWBp777V3Jzzs8y2N6oufkwWcTgHEyYDaVpaQz5k4IDgko6IsiOn11FCKwBnd0SBfUB3UA7YCKPAmKuu8RuUWhyC4z3zHNXPNsfyS95XsejYw9LDiEAoBhvX4B+kw9lipkEVCX0B6QmS8zF3gSUF45TDcI\/9jdcCGmiyhvrK1sZkmwsWSBxArShsA0DrpyxOGYkGN3MZkozEySPCZJWwH1mHGnF1mMalqI0fCiPx24O5tA6yX3xktwbrQX\/5kw1yQtOM8d\/15edFfm84QN2h21CPQA6\/nt58RSYZDg5iOesgEI5N+soazduQYDYCZJs+DWeAIabypLN9vQ8h6T32OPllm9TVEE+zoQ7dGApSKbG446zgEzWiyKV20PhWcwyMqRP+RhYg5gkaqYS9wd6mYgraSgpaNZALWgcJtoIs+JKxW4AcvyVXz2bi5Hp940Ns0G+IDr4OZIdRGfCiv5w2B9GLrQ4x3Ery5toqYY3iatGEX99wWdd0dribF\/Actm4FEfhtCiJY2aNDbeG949G\/RPxt2bGdrLnG3wRZwDdYuPAWyTnBqIEooAbMAtZ4oclXHbv1cWLPR8Fze\/e5RQsWT2kQwKUwLriPCV5GUOrZbLgYdiY1yJ+6GXaqJp4zcqig6c5xLqXvMR98dRIpuW\/LefphxKbygyCjqsKYYyNOZd3f1yaxAQlIIrcSGNkpbFOkICegAPAlba8d01Yfs+WV7LsoIQwzyCYRFADO64KIz4b1Qd5om1212NI2esCzWxm8VcXWcNvwnaXpOyIK+3BjgfDI3e2Jk6Id2NXn5ecFXPou0QM30MoCCZZLygBQLhmI2MbAyIuoNhLa9JfNw72tEeAxOvgMIlYbU1epLJplRLyS406WX+yUrGJN1tNC0TnYXxDcozxFeLEH9lhrBjVzN9ZUbM6NghpI9CC6TR\/bOxEi1d\/T\/FdAjMjar0RyWB\/ZLesw11RwZGFEX9OyS+IQhkjpwSHghAquNW8hWPGytjIr03xWQFhxe6QMECcVjvczTb3Iv2xCZXSqmdK+tl0o0uMr11qbRprs0hKHPzIMGu4vm6NSUsyPxjostTGimJEPLd40W2oe0h+DkZIdlUNJy0xrleCClgBkWjOERkWMVccE7cOy+7YaAYAKe4gl\/Gk66iMv2EMZz\/egxpD2iQgtBzObIhQwbeGehuyDrS2zeW4rJlxP9YDWTebQXg8GX62yvEPd\/9ZqWSxhr1b0GYTjQXFe+GqIddS4qDoMBqyRDLghEiSrK0AcGDW+RSGHbm0pTe3QHm1caoyr+Rc6bpywO8Hwd8g56YKI+c2ZWb0uqgMNrfES1ZQLUiuWE4ricV1BO9Qq\/J2SXxh3eGBMhScP2Z\/kUvP48j8DJdDzFxaPYrTouRhNA1DbySYd5AotlqTnYTTt3llGsmr3grrTc36SZSZSUnEWZv4Gx47TP123bMSRq2snli7Zs6iObfYohX\/1knqWWl+GPnJHL3XxTSnh\/DjNEGIQWadPhn6RZiLbGHW7nirhDO1VAzhWFLg2VgwwMyM0dceASkVawn7U3MYNPCUaCl57CpxygGFsBm90pBPqhgkrB+8\/\/\/+w790Gc7SJPhyZg1qAEUH1vS3cprT0\/4IsnBp7WJK5JlzfJhmqnKS8k\/\/TgqXEFxgkVWcKhvv0J7BEKv4Rvz0F7IePDmDzlOG8hfz+rPRRPz0pwvygxC\/UWRgIqk6I8o8K6YNyWRKB6cxhk03ek3HusgxKkekQG6q3Qh1Cg64wc8e6zLOHUKcl1B2immBLrVMB\/gskY+e\/PSDwNN47okpIFwphiMuNjSs9I42hHpWUpGjSB0XsxCH9S9NvMhjEK6bzGdsAzOfgV2xISstdx0NKSmp\/91\/UInHhi9ynX9ehEFPYyzU1hRYxWm+mUvCE6cyqyqgX1UnO0s7puNX1Zp3cLWy0FC3nUFfjDooZbKhGFoRi6vIzoiT9Ch4hp7MSZuivW0o3ibVItCMHcD30d5n3Xl8krzbycPl3Q6HnAMbjSYfTL2NbL7vgVJv3ZkfLPuGYTkBN7Z5rQdLwNF6jyc3o\/Hxg+bgMCyn4Q5HD5qGw7ATCPf4ATNxGNMm446G\/7eScWG+7dsw8grKOmzKFQEXp5Y0BT6UUJJUnVeVD2M\/ROnJ\/dqEEtdQfwCDocg+JyyqVioxbNMkqkTPxPqSCFAf7KipCooI8DOCW\/PjweLuHcZ3f58T4sdw9tJEQBS25Sm5SF9gWFIGpzuye4Zg1LgMKRbEb6kesmcIUc3hQVv+MtEgi6RTQDNMy\/qWwE+6nNG2CgXiAbjrnF8OUi3kk1yGR28kEzSjOicTaDNEn+Lcerq17IZJHOCdmaLD1KYQHnBaH0WFdSoKjpvKhvIJRWCJXKtIEquuYiLYBrmHBrlFDx7VOjewqNcFOYNOMEke7iY2kdMGm+\/QuTYggbI1tHvFG4gFOR\/4M7C4Zskv+yNOForyCC4kdWtvefj7y0SjfXEZbFj7UuUncUfHD+iOInYKw9Hwg+4IzzyoO+rM\/HDuKDLuaHgyeWB3FLE7Go7GD+uOInZH48OH9UYReaPh+EG9kfPvk+O\/gjfaLOr4rgi91nuzsyEgBAWLY77bZStzB4VWSZy46N\/5HoDHZZCncYnYlLs6TPWeXBPhcbFkv6Vdat5FbS5AT3WYbyqmr20to6ZEI4ebMQi\/ySo01NZCSMjZnqArDTC70dBAi8NUU1XUJh\/N8Bo5eP3IkCnM7+qweK7D4jyX3K27Me50w+f0HaiHHk+RmFUmrQThPRrb3xOkK8MUCB3IzuNvWxgA0ibU6+b32K3C+979m6kgzXD2HGyQqzO0wRZlaHMrmRVl6X2z6+jK3r8G3ahVzPJZcUTHz2+ZaAmsd6rYLcBRd0lhdMce3SB6TwaeLILLf9MmSYoBJTtN3ur7BhqQUuOG2dVGGfC+qvBX\/J85Nheuw5xNrYoLR07CnDryQatNNLpaVJgc2eisielkBqam9rF2QAxuRX0pprHT5irAo2xzDXHK3BthI0rEz7f5DZ9KnDHNoiVMY8prV8ocw6KY3\/2Ym0Ysm5PTtpj7ntOkpB6ZNqUlb2JXjg6T7544JZmvJVtzFUCCj9q5LYSnNj0nc\/Mvqz3pLS24ydQ8d6kxw0ZdGi9h\/JpWhSmLGDZKiQJ8lioLdWsYpumzuEptPg5CMznzadGYujp5pzivfaoiK6qFvIF4clvOnBICGy0wNtSPhv1oPIiOus2kz2W7NOBXErvim1slWP7dH2lSzNOmcW2zbRabh80Z2cR75ymg8ExlSzGVcYNwpzQdvj7xSECtZWmBuqi4Bk38ekmwaSq+rpSv2xYu1o1WNQBvnNhtjIq5Y+mV+1zsTGxqktqRSUUZWVwf5PlSUi9vLp7ScJk450Iwr38Po604SOHwquL9EJKSxisu55hyFIFLaTv9KLVoMkdeYXNX6nHAY4\/Ep2qMzd9LKdcRgpsDS8SUTrfqqmgYU31j35wiUgMcuak1SS7OwPGYM\/IFfm1z1P6Ng\/h1o615QYkrQnxKW4IOBGfuHQspvFjcppwudtvajmFMIVJKmtH8FGaUzimSdH2FD1FtrZY+My3Ov7uw9hg3Wqvuwz6AZW2RdSdE9k+58DfgBseDyCfGO0BnHZuyEalPVbsegrBBtesGqR2CVCLsbv2vf+p0t5YFSAybm0EpK313mnFDLeIryaK3q+9vpTsN9R84gFLsZwt6Rq+NaFXiVgObacmy3uzHpWcIy4jrUKtPxWkFxxVxQAb62kGck6EAkqsVNskRuwDQaosWNlM8LRRsLDeFQV8FZBeWAzzyxHmQVHLfcTjbRzqt565sevn06dWl6F2SCrpmTfHUjhqLpwpru7Kgq94aSVz6Fuc935TDogkkw4yrbT9OGqUVP8BRtzlcK2XYxqIoF9TmwhG4SaO7Gs\/3poJqj4OYYICzNXgRexHoi+iNDgfjo5\/+tCfg4ShvD7P8c+YH2t0C7RM1xC4leUliz\/i4wVYsPtSmQ8OUxEwdjdMHNj+\/NE1ZnnN4ehZ5cr09ZHlRTFuVNUBstcOZ5dbQBS\/\/0lkGlxtuZJUoLsObsmXY7u7qZ\/Xdn+u25GsbiDodQC5s6CBSslBVU82Vr+9p2yIb1CiJPlFFtS+4PmesgtwgNrW41XzczG3Zl3CfuO2ZDki\/LYZ1FGft0MKMfnQ6GEUbN0BaCuIvZNBvtIiiXtAplnQHJo1NzZP66PDIHM6htI86OHS1c9NBYWOUteYFztZJQ33ixBSLWvRqO3vWUoMM8kB4KohYWQFnUqfJ3BiHP8J6CeyW7NojwV1iNI4J+Jxj1V5tFwUFEmYMuAB31Hv7u+9c+WPW4bUBvUP+nY40OH56dH9XbB0dknTHVM0KuqA5auaaU6XmBAlmmG4syjhQcv\/TUtkukZVKB8NTEdt4HZukSzg\/uEVSwSzEfdY9l25tO+qCTkn4WPZahfKpxpGNphx2E\/i0VzsMMNnAP4jFOuhsXT6dM7MuRj9VJU3WtonBUvhmSkvz1xZDMiHCRyninFIJ7HqpM8JGOTG1DKWN9D18lBDHw5SO2daaBmag2a0j3lTc+fNx\/iLruEs+su4tGn27LH1bk2vV0oWx7P76tSqjBBx\/ZeZmU3hlZ19cIcDOySourq5MkXQVJ4nK7SW1lO7LxbXh+ybYcvrxmXh19Z3l2\/NKIUoXmrMULhXsIj9n8RDgAtJzwTePqKZNF5h+2DCFJmy7CRdXUuWYUj1aNvZ1P2a1baTtRmVK\/Gl3oXaNXWByAJ4r5lyBCZhlcShhZoBvSYzn7WZbVE7VbO+3RuPdOQXfHeG6VreG1QndmZo2eWpLzwRgdqVtFGFvu2yRR5MlttmKiSTw1p6oxZAwoLUM0cJH3+dDxHmTBA0b5srI0uiLTaLdZ1p7P2cXi3Cwtk1U3\/reB5skZO+CGASe1CDQzJYh4npbjyShXiBHn3hklbNl9DGBT8qtIzhwl8EywvCSeL5maNzCufWwNJeKOH1Qt3UYlySgpCSjHXHTWGX3zxL5tM17Kv7Yy0W4kl0e6JOWTf7\/9sz\/3575v397ZoPIXbRt2TvI2N0fEPALXyn4QmZz0xwYQKlE\/M9ZZo6q2P6CzrSd1zgCFKQaCI14K0yMFPLwjVIzp8NM9dq9J2+oCcB0CRctl\/ft8BY3\/a1ChtCUSZjLcflqDiVvTLr9Q3dgbULmgigeF7u1MAvh7k7TWQUaTr2pceOQ2tw0Nyiq2ZmZgMYO9jTgi5XMOFo2d\/a58dJc\/x2dDsb2NmDbotkmVtq74pzXWWujJiZn6yPEBhXHAnyNyNwYV0F4auM1jhTtOk3FhBzzxzFBSzjhDRa2tbnTwmsieJvWMTFRNzkZJK4dj9uIbXZUJWyyweSrIZPXxLCNr3Ou7jeI8IrK3W\/iqM2lKk106aQmO916xZQSmT4x0\/GIjmGrVK7d8WhcT3e33b6TleKTY90z1FgEFCTpmp\/J2xn9YIuYES8NaNotd11kJHpV7fs0tQkQRHuwHMCnxDJcZcnfopndveOL+YjZL766fHklehcLmbwRX9nuY3HpW+1fVtIZyxUYSqP3uGDJpK2K6XhX4CB0BJQOpKviHO4A6o4NxaAaRJlR67lN8+4kT6Y3+L5X2imBWLgWv7ZBlS5MyyDHLl31NW0S24m7xqh6RgX2bKp242K2D7K0RULfxoP\/jcCr9Y5LbwHoOajqC26ugeCCK2xtlZMVPsyotDfPdkD+q7YBR+8C\/eG+eKFqNlTR+2J\/z1596gsulEsuUtYF8AkiornzgQvSiko4pi5T35s+iJPvqbqV+oglPgPSU0+7JKkn9AUBSsJhGTUST6H8X0mQn0UfijE87WOSlYjGvfHeWRSdDqLRqdXjCEtt8qoQvav9vb74In4Ds+o9pZ9f0fJA4whWNOYuKPjkcyw4sd5QOtLspDQ6e4+tiHYrMndfjFKLGqfyVJI2s8oWM4StNU4N6HU+o35gaBlBpMKL38C4aFnuuyF4i5O+GI\/x\/8ngaGS3Ntq3X0sClL0wMQ+0lGQjqWYS2Bk8nLnmWWR04VCxO5Cuc4r185bWtGCRsgiCrYWXQDEQhX1LlcALKrpZoanO0C4kTihJyEM4kVDcXRfJm0WRLc\/4HvtnZM1ju43xfnAqXpMuzdeG0KK6SlKHWiKwORLtC0mwVHlW4BXF7lr8Il6WnzEaiWclEHepiqzPq4BMj\/piNDwejKKhXdIRfQfHXJF2XwVruljE+ZxzPaH4OnIbbJcb3vj2qhVIX3wDA59n4mtauT3f0clpf+jO9nhffF1Q\/gbm9SwUi+\/0oqMomhqgRXW82ZpqDu5nZbSwaDLuLA5HStonnedJ1q7NIliTlYr74uvzF+fiG1lfF9UbmAx91wUEOuqL497R3pmMRsPxcHJkN3QS2qHfzjfEB7w5fQAOkhgHAmM07TP3P+IhjjjqTWDxp6fDwenpsVnRBCJWovfbYDlPJXdgmKIYqTpwQWtnsbZjZrWG6Klse1LI\/vL77imQoBcfQVkkesPDPdEX8nQ4Oj4Zm+WeEgmR0Aqy3gvQVpNZ73s7x5l9xNR\/1yi456t4Jutb0Bmt4Y6OISmqDbPQ7LkND\/cFfeEE5vFK0\/tuq5797rvzl79nuXV1MXikHeN3L7959u3v98SzFdOZ13HexNUt5xn7otzHtHZ++JrfFtkMLGRK35wDmDh\/z4kFF4dwYnGnqxfzd1tS2b0MEN1fQ6EhPkKSWUUtqvYcf4ZB9fIVf69T6dEXuEEXdakl44WBTSqG3vJyPSvyZ4\/dD8fRZF+eDMy\/HhKG7MrMVeOPkIFmQ2Yv4Np7jZ7G695sc1tbpfemI7577y5ilD07mkSDo8mJ29OIkLaiL2fhPfXFd1SbfJ1OCczfKvlG5gsu8fFIQDo4RW7SIppo9ykHhZzxl8md0etzmanXb\/jzPPgamc7Rz+WcjoeTTi\/oGhfxv3\/w0\/mPVwXkMs0KmYJFFsWyXQdevMgK\/FWlqlCuU41J1yCNq+U19Zq4p\/vBOpYx9mvy6VYG420aTq8sZFW1v8Y3ovcV\/XS+XZ1\/pg+QTmXXGFdGMA96Tje0LPk6f3V5YZymGI7ORt5E2V3mb0lWvV8ys1pIDHtBP\/4qA6tGENJ7wZvoKhRVHhCLzZosuxU7rHRWfFhPAzcxL8iSZ9wXgXMuslRcL3BYU7iyt6AqVB3PyNLpywP0R2pvXxwdHg6ODiO382OiNrLKyauFbvrZB5znzweYszWnVEHbTQv+bWv8ijD9Hu7R+msilsOT49PB8OTEayUc9ncwoBd0Y+INH5\/f3ctX55dXz87geag4QvKORVXE6TIuDbL4k2wvWHfEoNov1CP5t7K3i3ZuOzo5uxoNho7LD+Gyv1QNNgw76v0qWBF5Rul2RQdojOF+SkPLIej\/Fl4cf6eglEz2fAl61hWiY+Ir4tHjY0Qd1b6AAEdRBPboQQ2umjLOt6L3rMt17h87BGsLCZ8hmi3vi\/HQnNibjyZmVbGkVR4PIEL47h27iCLocnTYH+LBoRcwvfAeZxtEFP8bwnl1req3soIqpIQ59W2J6F4sbqfAUvcVKxgYSj7wl4mNOwPaUsT7nJSotspF8Y4jntHobDI6HkzGx25DYA8hAu0IVF14t307AWva\/gC\/rB3zub\/SbYuVzsyXBjYlPJu8P8fFcY6JeU9OBieeMURgDOB5ed4N0tcUcXvwssU9TM3tT6LfiTQcouxqhM0q7tK5Q4pf8XE0Gpx7a4lAAZ5TBzzZS1fb3Ey7A\/D3WA6pVh5XFWdIvQv72ggvgBnCvqMhW\/YgGjpkR3Qqni0qCZ9hCNfVpjMLGhchm\/paUgUrVnBldVHUi2nV6AWDY\/7xmQ5+aSnreGC+84F0nKMF21CVmZBX5dJvYjLuRVjVcDQk5mi3Add8USmcW0f7f+0zHSrviDQwXvWWFmkzpLvPFH7xiCzv5GQQTSZ2VrjFV4WOK1V0Ne8Ztdt7Zsq5twFn3XJ7qzfoGtmiXv6r\/bpmBB9P\/SwphtMkTHsX4i1F1olZaoa9WPDwmYovpWldTLqihCoMYU3Dw\/HRYHh45Pwh9FV8WdER957T4e80IrENOVojsr2Qt\/ewksNB5NURnu8lBo4pgOb5v4orcGT4AqOZz6kDmtLmhnV1kfoDMLSmACzI8OQt6xvC3x2djT24wMt9QS3BonfZ9REQr7U61x2F38tbPlHys91T9Q0qiP74G618FTue0b3NpizpdKd0pKT3IBJwTLdnhERzNpm+SLkDF0RdQQqpUazEZMTcxRj8eVMXvnjxNXv0s9Hx4dnro9Oh8xvgtuKikRqQ9DLYHGcMeeGWMrTeGTspEQ5QmPBGblfV6a1NrdCbINb5YFlM24zV1+SU6OULcFPQ1VWsE+fchodnw9PecA\/IOXFLHHJaLYPXzNf4GbOhuAIQLQtLDU1mmqGGfSrilwV5UUcj3RldL+hbUZbxrUvednb4PkUiwMpkPid6MqN++ts1tKVtjPuTCbYxGg98gnZETmotD7MbWWOEDNQpRPDh9hYnCwXQhGDTxsXxvBniyT5tubl2qON2PhZsivkVsXaKETA\/5QRb0\/ia4Tin7802PQY2m0dcZDTpHcESx8PJYOxznSM4u1cvvqRASL0t8CZ3k4U9WrZ5C\/QnP7hmRORHsiZZQA7zIKQMUqgjeKsBYmfXLkT3f+dUJ+ONvCnevKF4uAfaek3RA8YmBPnyFfPX0+OTscn7yCVYH7MJNy7cx6\/itzEFgRR7+gN6DrEMqI2Y1k64a7ItZAGB9XsxBhZv1d1HaCp3Lfra9oKK67hKrbe7wt\/6RnHEcHzaO6Uk3nA8OB16MzimymBCPpGxr9UhDJiAPSC49JOWH0qViR1ETWR8wcA9dn9eRmBOYeP4ZHB05MUKX5JKaLnqstKPK5j+xnxXoc2Sx674FJClD9FPIOKCjqEbLAVuX5hmKkl0wTct32vz+23mlXzpIbV6uN3Dl11RvhMH9k0ntR30BrfVow2Y\/blhsyhVVkDN6iZ9j\/eF5RIbHI6i8QD\/8Wp2Sp1zKwpgrce9HwGQIQMYGApQx2+YFiZupzhFwH37pVY2ursHRZgMzkeOoYwPiSMYWzJ5XQTvtjngl0Vjmxw+UsnWdvnVhoRfbmzQbsx8D4OzbbMe910NBr2i\/Q9+wQN1eO364\/8A\" \/><\/form> \t<div class=\"pdf24Plugin-cp-link\"> \t\t<a href=\"#\" onclick=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); document.pdf24Form0.submit(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));} return false;\">Download article as PDF<\/a> \t<\/div> <\/div>","protected":false},"excerpt":{"rendered":"<p><strong>La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.<\/strong><\/p>\n","protected":false},"author":2,"featured_media":1798424,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-1804476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-117"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"LR\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"NOSO INFO - - Bulletin pour la pr\u00e9vention et la ma\u00eetrise des infections associ\u00e9es au soins\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO\" \/>\n\t\t<meta property=\"og:description\" content=\"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-12-30T09:29:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-30T09:29:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#blogposting\",\"name\":\"La pr\\u00e9vention des pneumonies nosocomiales non-associ\\u00e9es \\u00e0 la ventilation (nv-HAP): un (nouveau) d\\u00e9fi pour les \\u00e9quipes de pr\\u00e9vention et de contr\\u00f4le des infections (EPCI) - NOSO INFO\",\"headline\":\"La pr\\u00e9vention des pneumonies nosocomiales non-associ\\u00e9es \\u00e0 la ventilation (nv-HAP): un (nouveau) d\\u00e9fi pour les \\u00e9quipes de pr\\u00e9vention et de contr\\u00f4le des infections (EPCI)\",\"author\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/az_groeninge_kortrijk-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"BE, Kortrijk, 06\\\/2011, Hospital AZ Groeninge,  Architekt: Baumschlager Eberle Vaduz, Bildtechnik: Digital-KB\"},\"datePublished\":\"2025-12-30T10:29:58+01:00\",\"dateModified\":\"2025-12-30T10:29:58+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#webpage\"},\"articleSection\":\"325\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/category\\\/325\\\/#listItem\",\"name\":\"325\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/category\\\/325\\\/#listItem\",\"position\":2,\"name\":\"325\",\"item\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/category\\\/325\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#listItem\",\"name\":\"La pr\\u00e9vention des pneumonies nosocomiales non-associ\\u00e9es \\u00e0 la ventilation (nv-HAP): un (nouveau) d\\u00e9fi pour les \\u00e9quipes de pr\\u00e9vention et de contr\\u00f4le des infections (EPCI)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#listItem\",\"name\":\"Accueil\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#listItem\",\"position\":3,\"name\":\"La pr\\u00e9vention des pneumonies nosocomiales non-associ\\u00e9es \\u00e0 la ventilation (nv-HAP): un (nouveau) d\\u00e9fi pour les \\u00e9quipes de pr\\u00e9vention et de contr\\u00f4le des infections (EPCI)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/category\\\/325\\\/#listItem\",\"name\":\"325\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/#organization\",\"name\":\"NOSO INFO\",\"description\":\"- Bulletin pour la pr\\u00e9vention et la ma\\u00eetrise des infections associ\\u00e9es au soins\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/wp-content\\\/themes\\\/nosoinfo\\\/images\\\/header-titre.png\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#author\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\",\"name\":\"LR\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2c5b1ecacf5e19c0d8e228bb313ac467fcd9a82f3cbde10c777c17a8ef5b875?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"LR\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#webpage\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/\",\"name\":\"La pr\\u00e9vention des pneumonies nosocomiales non-associ\\u00e9es \\u00e0 la ventilation (nv-HAP): un (nouveau) d\\u00e9fi pour les \\u00e9quipes de pr\\u00e9vention et de contr\\u00f4le des infections (EPCI) - NOSO INFO\",\"description\":\"La pneumonie est l\\u2019infection associ\\u00e9e aux soins de sant\\u00e9 (IAS) la plus courante dans le monde et est associ\\u00e9e \\u00e0 une morbidit\\u00e9, une mortalit\\u00e9 et un co\\u00fbt importants.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/az_groeninge_kortrijk-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#mainImage\",\"width\":2560,\"height\":1707,\"caption\":\"BE, Kortrijk, 06\\\/2011, Hospital AZ Groeninge,  Architekt: Baumschlager Eberle Vaduz, Bildtechnik: Digital-KB\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\\\/#mainImage\"},\"datePublished\":\"2025-12-30T10:29:58+01:00\",\"dateModified\":\"2025-12-30T10:29:58+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/#website\",\"url\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/\",\"name\":\"NOSO INFO\",\"description\":\"- Bulletin pour la pr\\u00e9vention et la ma\\u00eetrise des infections associ\\u00e9es au soins\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nosoinfo.be\\\/nosoinfos\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO","description":"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.","canonical_url":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#blogposting","name":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO","headline":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)","author":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos#author"},"publisher":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-scaled.jpg","width":2560,"height":1707,"caption":"BE, Kortrijk, 06\/2011, Hospital AZ Groeninge,  Architekt: Baumschlager Eberle Vaduz, Bildtechnik: Digital-KB"},"datePublished":"2025-12-30T10:29:58+01:00","dateModified":"2025-12-30T10:29:58+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#webpage"},"isPartOf":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#webpage"},"articleSection":"325"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos#listItem","position":1,"name":"Accueil","item":"https:\/\/www.nosoinfo.be\/nosoinfos","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/#listItem","name":"325"}},{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/#listItem","position":2,"name":"325","item":"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#listItem","name":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos#listItem","name":"Accueil"}},{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#listItem","position":3,"name":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/#listItem","name":"325"}}]},{"@type":"Organization","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/#organization","name":"NOSO INFO","description":"- Bulletin pour la pr\u00e9vention et la ma\u00eetrise des infections associ\u00e9es au soins","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/","logo":{"@type":"ImageObject","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/themes\/nosoinfo\/images\/header-titre.png","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#organizationLogo"},"image":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.nosoinfo.be\/nosoinfos#author","url":"https:\/\/www.nosoinfo.be\/nosoinfos","name":"LR","image":{"@type":"ImageObject","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c2c5b1ecacf5e19c0d8e228bb313ac467fcd9a82f3cbde10c777c17a8ef5b875?s=96&d=mm&r=g","width":96,"height":96,"caption":"LR"}},{"@type":"WebPage","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#webpage","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/","name":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO","description":"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/#website"},"breadcrumb":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#breadcrumblist"},"author":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos#author"},"creator":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-content\/uploads\/2025\/12\/az_groeninge_kortrijk-scaled.jpg","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#mainImage","width":2560,"height":1707,"caption":"BE, Kortrijk, 06\/2011, Hospital AZ Groeninge,  Architekt: Baumschlager Eberle Vaduz, Bildtechnik: Digital-KB"},"primaryImageOfPage":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/#mainImage"},"datePublished":"2025-12-30T10:29:58+01:00","dateModified":"2025-12-30T10:29:58+01:00"},{"@type":"WebSite","@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/#website","url":"https:\/\/www.nosoinfo.be\/nosoinfos\/","name":"NOSO INFO","description":"- Bulletin pour la pr\u00e9vention et la ma\u00eetrise des infections associ\u00e9es au soins","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.nosoinfo.be\/nosoinfos\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"NOSO INFO - - Bulletin pour la pr\u00e9vention et la ma\u00eetrise des infections associ\u00e9es au soins","og:type":"article","og:title":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO","og:description":"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants.","og:url":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/","article:published_time":"2025-12-30T09:29:58+00:00","article:modified_time":"2025-12-30T09:29:58+00:00","twitter:card":"summary","twitter:title":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI) - NOSO INFO","twitter:description":"La pneumonie est l\u2019infection associ\u00e9e aux soins de sant\u00e9 (IAS) la plus courante dans le monde et est associ\u00e9e \u00e0 une morbidit\u00e9, une mortalit\u00e9 et un co\u00fbt importants."},"aioseo_meta_data":{"post_id":"1804476","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2025-12-29 09:11:56","updated":"2026-07-06 09:38:34","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosoinfo.be\/nosoinfos\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/\" title=\"325\">325<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/www.nosoinfo.be\/nosoinfos"},{"label":"325","link":"https:\/\/www.nosoinfo.be\/nosoinfos\/category\/325\/"},{"label":"La pr\u00e9vention des pneumonies nosocomiales non-associ\u00e9es \u00e0 la ventilation (nv-HAP): un (nouveau) d\u00e9fi pour les \u00e9quipes de pr\u00e9vention et de contr\u00f4le des infections (EPCI)","link":"https:\/\/www.nosoinfo.be\/nosoinfos\/la-prevention-des-pneumonies-nosocomiales-non-associees-a-la-ventilation-nv-hap-un-nouveau-defi-pour-les-equipes-de-prevention-et-de-controle-des-infections-epci\/"}],"_links":{"self":[{"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/posts\/1804476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/comments?post=1804476"}],"version-history":[{"count":3,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/posts\/1804476\/revisions"}],"predecessor-version":[{"id":1804493,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/posts\/1804476\/revisions\/1804493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/media\/1798424"}],"wp:attachment":[{"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/media?parent=1804476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/categories?post=1804476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nosoinfo.be\/nosoinfos\/wp-json\/wp\/v2\/tags?post=1804476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}